{"id":3292,"date":"2022-05-29T10:46:46","date_gmt":"2022-05-29T14:46:46","guid":{"rendered":"https:\/\/baiedurfe.ca\/?p=3292"},"modified":"2022-05-29T10:46:46","modified_gmt":"2022-05-29T14:46:46","slug":"le-10-mai-2022","status":"publish","type":"post","link":"https:\/\/baiedurfe.ca\/fr\/le-10-mai-2022\/","title":{"rendered":"Le 10 mai 2022"},"content":{"rendered":"<p>Aper\u00e7u \u2013 S\u00e9ance du Conseil Municipal du 10 mai 2022<\/p>\n<p>La r\u00e9union a eu lieu en personne \u00e0 Whiteside Taylor et \u00e9tait \u00e9galement offerte en conf\u00e9rence vid\u00e9o.<\/p>\n<p>Ces notes repr\u00e9sentent un r\u00e9sum\u00e9.\u00a0 La<a href=\"https:\/\/www.webtv.coop\/group\/video\/Seance-du-conseil-municipal-de-Baie-D039Urfe-10-mai-2022\/615d697df43c551881ba1267fb66be68\/5d4ed6dabc49908f6311a3ad3567dc90\"> r\u00e9union<\/a> et<a href=\"https:\/\/www.baie-durfe.qc.ca\/medias\/en\/documents\/2022-05-10_ODJ_Agenda_Bilingual.2.pdf\"> l\u2019ordre du jour<\/a> se trouvent, dans leur enti\u00e8ret\u00e9,\u00a0 sur le site\u00a0 de la Ville.<\/p>\n<p><em>Le texte en italique indique le marqueur de minute de la conf\u00e9rence vid\u00e9o pour une r\u00e9f\u00e9rence rapide.<\/em><\/p>\n<p>Mairesse Ektvedt a ouvert la s\u00e9ance \u00e0 19h30.<\/p>\n<p><strong>Questions en ligne <\/strong><em>Minute 1\u00a0:40<\/em><\/p>\n<p><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/em>. Les pistes cyclables sur Lakeshore ouest ne seront pas \u00e9largies \u00e0 cause des arbres existants et l\u2019\u00e9troitesse du Lakeshore. Lakeshore est sera discut\u00e9 lors de la r\u00e9habilitation du Lakeshore en 2023.<\/p>\n<p>. Les changements au r\u00e8glement des piscines sont mandat\u00e9s par les \u00a0\u00a0 lois provinciales et, par cons\u00e9quent, la Ville suivra les directives du \u00a0\u00a0 gouvernement. La mise en \u0153uvre de ce r\u00e8glement a \u00e9t\u00e9 report\u00e9e \u00e0 30\u00a0\u00a0 septembre 2025.<\/p>\n<p>. Le m\u00e2t du drapeau historique du parc Bertold est examin\u00e9 pour d\u00e9terminer l\u2019\u00e9tendue des dommages caus\u00e9s par les pics-bois.<\/p>\n<p>. <em>Minute 9\u00a0:08 <\/em>L\u2019actuel H\u00f4tel de Ville n\u2019est pas conforme aux r\u00e8glements existants et le projet avec les r\u00e9novations propos\u00e9es ne\u00a0 l\u2019est pas non plus, d\u2019o\u00f9 la demande d\u2019une d\u00e9rogation mineure. La hauteur du b\u00e2timent propos\u00e9 sera la m\u00eame que la hauteur du b\u00e2timent actuel. Le projet de l\u2019H\u00f4tel de Ville n\u2019attendra pas la r\u00e9vision du r\u00e8glement municipal \u00e9tant donn\u00e9 que cela prendra \u00a0\u00a0 quelques ann\u00e9es \u00a0\u00a0\u00a0\u00a0\u00a0 pour \u00eatre compl\u00e9t\u00e9 et le Conseil poursuivra le projet de la demande de d\u00e9rogation sans d\u00e9lai. Le comit\u00e9 consultatif \u00a0\u00a0\u00a0\u00a0 d\u2019urbanisme a recommand\u00e9 la r\u00e9novation et elle est conforme au SPAIP.<\/p>\n<p>. Les Travaux Publics sont ad\u00e9quatement form\u00e9s et assument la responsabilit\u00e9 de l\u2019abattage et \u00e9lagage des arbres. Par cons\u00e9quent, un \u00a0\u00a0\u00a0 comit\u00e9 de b\u00e9n\u00e9voles pour assumer ce r\u00f4le n\u2019est pas n\u00e9cessaire.<\/p>\n<p><strong>\u00a0<\/strong><strong>Rapport du Commandant Couture <\/strong><em>Minute 15\u00a0:30<\/em><\/p>\n<p><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/em>. L\u2019op\u00e9ration d\u2019exc\u00e8s de vitesse sur St Andrew et Churchill a \u00e9t\u00e9 effectu\u00e9e<\/p>\n<p>. Des policiers \u00e0 v\u00e9lo sont pr\u00e9sents dans diff\u00e9rents parcs et pendant les heures d\u2019\u00e9cole.<\/p>\n<p>. Aucun \u00e9v\u00e9nement criminel majeur n\u2019a \u00e9t\u00e9 observ\u00e9 \u00e0 Baie-D\u2019Urf\u00e9 bien que sur Apple Hill, Winters et Lorraine une Hyundai Elantra aux vitres teint\u00e9es a \u00e9t\u00e9 observ\u00e9e. Tous les v\u00e9hicules \u00e9taient d\u00e9verouill\u00e9es.<\/p>\n<p><strong>Rapport de la Mairesse <\/strong><em>Minute 19\u00a0:21<\/em><\/p>\n<p><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/em>. La Mairesse a remerci\u00e9 chaleureusement la greffi\u00e8re, Tania L\u00ea, qui quitte pour une autre opportunit\u00e9. Elle a \u00e9galement remerci\u00e9 l\u2019ancien \u00a0\u00a0 conseiller Nick Drouin pour ses services.<\/p>\n<p>. R\u00e9unions sp\u00e9ciales du Conseil\u00a0:<\/p>\n<p>. Le 21 avril il y a eu un conseil sp\u00e9cial relatif au pavage de Sunny Acres et Lakeview<\/p>\n<p>. Le 4 mai \u00e0 propos de modifications concernant des r\u00e8glements municipaux<\/p>\n<p>. Le 5 mai il y eut une r\u00e9union du comit\u00e9 de d\u00e9molition. Cela a\u00a0 \u00e9t\u00e9 enregistr\u00e9 et est maintenant disponible en ligne<\/p>\n<p>. Diff\u00e9rentes r\u00e9unions annuelles ont eu lieu\u00a0: le club de tennis et l\u2019\u00c9quipe de secours ( r\u00e9sum\u00e9 de l\u2019ann\u00e9e fourni )<\/p>\n<p>. Remerciements \u00e0 l\u2019Association des Citoyens pour l\u2019\u00e9v\u00e9nement de la \u00a0\u00a0 f\u00eate des M\u00e8res<\/p>\n<p>. L\u2019Association des Citoyens d\u00e9butera les Rendez-vous des Seniors<\/p>\n<p><strong>Rapports des Conseillers<\/strong><\/p>\n<p>Conseill\u00e8re Lowensteyn <em>Minute 25\u00a0:54<\/em><\/p>\n<p>. A fait rapport du Conseil des Juniors, tenu le 31 mai \u00e0 19h30 dans le Gazebo the Fritz. Bienvenue aux nouveaux membres.<\/p>\n<p>. A rappel\u00e9 aux citoyens le r\u00e8glement municipal concernant les \u00a0\u00a0 nuisances et la restriction relative \u00e0 l\u2019usage d\u2019\u00e9quipement de \u00a0 pelouses les longues fins de semaine.<\/p>\n<p>. La biblioth\u00e8que cherche des b\u00e9n\u00e9voles pour son comptoir de pr\u00eat de livres<\/p>\n<p>Conseill\u00e8re Bissada <em>Minute 28.03<\/em><\/p>\n<p>. Remerciements \u00e0 l\u2019Association des Citoyens pour le d\u00e9je\u00fbner de la f\u00eate des M\u00e8res<\/p>\n<p>. R\u00e9union annuelle du Tennis et nouveau gazebo au Club de Tennis<\/p>\n<p>. D\u00e9but de la pr\u00e9-saison du Centre aquatique de Baie-D\u2019Urf\u00e9 le 11 juin<\/p>\n<p>. Les Rendez-Vous des Seniors, organis\u00e9s par l\u2019Association des Citoyens et les VCops, d\u00e9butent le 19 mai, de 13 \u00e0 16h. Les places \u00a0 sont limit\u00e9es et seront accord\u00e9es sur une base de premier arriv\u00e9, \u00a0\u00a0\u00a0\u00a0 premier servi. SVP, contactez Irene Perstinger ( 514-457-5858 ou\u00a0 <a href=\"&#109;&#97;&#x69;l&#116;&#x6f;&#x3a;p&#101;&#x72;&#x73;t&#105;&#x6e;&#x67;e&#114;&#x40;&#x76;i&#100;&#x65;&#x6f;t&#114;&#x6f;n&#46;&#99;&#x61;\">&#112;&#x65;&#114;&#x73;&#116;&#x69;n&#x67;e&#114;&#x40;&#118;&#x69;&#100;&#x65;o&#x74;r&#111;&#x6e;&#46;&#x63;&#97;<\/a> )<\/p>\n<p>. Rappelle que c\u2019est un mois de mai \u00ab sans tonte \u00ab . Essayons de retarder la tonte de nos pelouses pour prot\u00e9ger la biodiversit\u00e9.<\/p>\n<p>Conseiller Gruber <em>Minute 33\u00a0:06<\/em><\/p>\n<p>. Le Yacht Club est ouvert \u2013 des b\u00e9n\u00e9voles ont construit des nouveaux quais et les ont mis \u00e0 l\u2019eau ainsi que les yachts.<\/p>\n<p>. La garde c\u00f4ti\u00e8re a commenc\u00e9 ses patrouilles et a secouru plusieurs\u00a0 kayakistes sous-estimant la force des courants<\/p>\n<p>. Encourage un mois de mai \u00ab\u00a0sans tonte\u00a0\u00bb<\/p>\n<p><strong>Rapport du Directeur G\u00e9n\u00e9ral <\/strong><em>Minute 35\u00a0:47<\/em><\/p>\n<p>. Plusieurs postes sont vacants et seront \u00e0 l\u2019ordre du jour du conseil de\u00a0 juin. Il s\u2019agit notamment d\u2019un nouveau technicien en environnement, d\u2019un inspecteur de l\u2019urbanisme, d\u2019un technicien en Sports et Loisirs ,\u00a0 d\u2019un greffier adjoint et d\u2019un greffier municipal<\/p>\n<p>. Appel d\u2019offres report\u00e9 pour l\u2019H\u00f4tel de Ville en raison des questions des entrepreneurs g\u00e9n\u00e9raux. L\u2019Appel d\u2019offres sera d\u00e9sormais ouvert le\u00a0 16 mai<\/p>\n<p>. Remercie Tania L\u00ea pour ses services rendus \u00e0 la Ville<\/p>\n<p><strong>Correspondance <\/strong><em>Minute 39\u00a0:01<\/em><\/p>\n<p><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/em>. Pr\u00e9occupation concernant l\u2019\u00e9tat du m\u00e2t du centenaire, en raison des\u00a0 dommages caus\u00e9s par les pics-bois. S\u2019il est jug\u00e9 dangereux de l\u2019utiliser comme m\u00e2t de drapeau, plusieurs suggestions ont \u00e9t\u00e9 propos\u00e9es pour le prot\u00e9ger.<\/p>\n<p><strong>Administration <\/strong><em>Minute 42\u00a0:03<\/em><\/p>\n<p>. Le si\u00e8ge 1 a \u00e9t\u00e9 lib\u00e9r\u00e9 le 2 mai 2022 et fera partie de l\u2019\u00e9lection partielle du dimanche 17 juillet 2022.<\/p>\n<p>. L\u2019agglom\u00e9ration a augment\u00e9 le coefficient et la Ville a chang\u00e9 de conseiller juridique pour repr\u00e9senter la Ville aux c\u00f4t\u00e9s des villes d\u00e9fusionn\u00e9es<\/p>\n<p>. Deux \u00e9tudiants ont \u00e9t\u00e9 engag\u00e9s pour l\u2019 Urbanisme<\/p>\n<p>. Pendant les restaurations de l\u2019H\u00f4tel de Ville, les employ\u00e9s qui \u00a0y travaillent \u00e0 pr\u00e9sent, d\u00e9m\u00e9nageront au Parc Industriel pour 24 mois \u00e0\u00a0 partir du 1<sup>er<\/sup> juin 2022 jusqu\u2019au 31 mai 2024<\/p>\n<p>. Madame Susan McKercher a \u00e9t\u00e9 nomm\u00e9e Pr\u00e9sidente de l\u2019\u00c9lection\u00a0 partielle qui se tiendra le 17 juillet 2022. Les salaires ( $ 85,500 ) pour le personnel suppl\u00e9mentaire requis pour organiser l\u2019\u00e9lection a aussi \u00e9t\u00e9 autoris\u00e9<\/p>\n<p><strong>Finance <\/strong><em>Minute 55\u00a0:31<\/em><\/p>\n<p><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/em>. Les d\u00e9penses du mois \u00e9taient de $ 643,267. Le rapport financier et le rapport du commissaire aux comptes sont disponibles sur le site de la Ville et la mairesse en parlera dans l\u2019 \u00ab Entre-Nous \u00bb du mois de juin. Le surplus se monte actuellement \u00e0 $ 3.252 million<\/p>\n<p><strong>\u00a0<\/strong><strong>Parc, Loisirs et environnement<\/strong> <em>Minute 58\u00a0:03<\/em><\/p>\n<p><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/em>. Autorisation de signataire pour le MELCC pour que Baie-D\u2019Urf\u00e9 obtienne les droits sur une partie du bord de l\u2019eau, pr\u00e8s de l\u2019H\u00f4tel de Ville, qui a \u00e9t\u00e9 pourvu avant 1993.<\/p>\n<p>. La ville fera partie d\u2019un effort multi-villes ( villes d\u00e9fusionn\u00e9es ) pour demander un financement du gouvernement f\u00e9d\u00e9ral pour la plantation d\u2019arbres<\/p>\n<p><strong>Travaux Publics et Infrastructure de la Ville<\/strong> <em>Minute 1\u00a0:05\u00a0:33<\/em><\/p>\n<p><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/em>. La r\u00e9paration des fissures d\u2019asphalte \u00e0 \u00e9t\u00e9 attribu\u00e9e. Les travaux commenceront par Surrey, Oakridge et Normandy.<\/p>\n<p>. Le contrat de nettoyage des parcs et tonte de l\u2019herbe a \u00e9t\u00e9 reconduit pour un an selon les modalit\u00e9s du contrat.<\/p>\n<p><strong>Urbanisme<\/strong> <em>Minute 1\u00a0:09\u00a0:06<\/em><\/p>\n<p><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/em>. Embauche d\u2019un cabinet d\u2019avocats pour la ville, concernant les non- conformit\u00e9s de la hauteur du 706 Westchester<\/p>\n<p>. Adoption, sans aucun changement, de la modification du r\u00e8glement \u00a0 municipal de zonage 875-126 pour cr\u00e9er la zone 1-53<\/p>\n<p>. Adoption, sans aucun changement, de la modification du r\u00e8glement \u00a0 municipal 877-13 concernant la pente des fonds de piscine<\/p>\n<p>. Adoption, sans aucun changement, de la modification du r\u00e8glement \u00a0 municipal 878-30 pour augmenter les amendes pour la coupe d\u2019arbres<\/p>\n<p>. Adoption, sans aucun changement, de la modification du r\u00e8glement \u00a0 municipal 961-7 concernant les exemptions mineures<\/p>\n<p><strong>Services aux citoyens et Affaires Communautaires<\/strong> <em>Minute 1\u00a0:26\u00a0:11<\/em><\/p>\n<p><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/em>. Le programme des concerts d\u2019\u00e9t\u00e9 dans le parc a \u00e9t\u00e9 approuv\u00e9<\/p>\n<p>. Approbation pour aller en appel d\u2019offres (en tant que groupe avec d\u2019autres municipalit\u00e9s ) pour obtenir une couverture d\u2019assurance pour\u00a0 les organisations sans but lucratif de la Ville.<\/p>\n<p><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/em>. Approbation des fonds annuels allou\u00e9s aux organisations sans but lucratif, soutenus par la Ville<\/p>\n<p>. Autorisation pour la tenue de l\u2019\u00e9v\u00e9nement Shakespeare-in-the-park \u00a0 \u00ab\u00a0All will be well\u00a0\u00bb , le vendredi 5 ao\u00fbt 2022<\/p>\n<p><strong>P\u00e9riode de Questions II<\/strong> <em>Minute 1:29:55<\/em><\/p>\n<p><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/em>. Un citoyen a propos\u00e9 un libell\u00e9 alternatif pour la modification du r\u00e8glement 961-7 concernant le libell\u00e9 de la page 2<\/p>\n<p>La s\u00e9ance a \u00e9t\u00e9 cl\u00f4tur\u00e9e \u00e0 21h15<\/p>\n<p>Rapport d\u2019Andrea Gilpin pour \u00ab\u00a0Entre Nous\u00a0\u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aper\u00e7u \u2013 S\u00e9ance du Conseil Municipal du 10 mai 2022 La r\u00e9union a eu lieu en personne \u00e0 Whiteside Taylor et \u00e9tait \u00e9galement offerte en conf\u00e9rence vid\u00e9o. Ces notes repr\u00e9sentent un r\u00e9sum\u00e9.\u00a0 La r\u00e9union et l\u2019ordre du jour se trouvent, dans leur enti\u00e8ret\u00e9,\u00a0 sur le site\u00a0 de la Ville. Le texte en italique indique le [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[18],"tags":[],"class_list":["post-3292","post","type-post","status-publish","format-standard","hentry","category-extraits-du-conseil-municipal"],"_links":{"self":[{"href":"https:\/\/baiedurfe.ca\/fr\/wp-json\/wp\/v2\/posts\/3292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/baiedurfe.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/baiedurfe.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/baiedurfe.ca\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/baiedurfe.ca\/fr\/wp-json\/wp\/v2\/comments?post=3292"}],"version-history":[{"count":2,"href":"https:\/\/baiedurfe.ca\/fr\/wp-json\/wp\/v2\/posts\/3292\/revisions"}],"predecessor-version":[{"id":3294,"href":"https:\/\/baiedurfe.ca\/fr\/wp-json\/wp\/v2\/posts\/3292\/revisions\/3294"}],"wp:attachment":[{"href":"https:\/\/baiedurfe.ca\/fr\/wp-json\/wp\/v2\/media?parent=3292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/baiedurfe.ca\/fr\/wp-json\/wp\/v2\/categories?post=3292"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/baiedurfe.ca\/fr\/wp-json\/wp\/v2\/tags?post=3292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}