{"id":4002,"date":"2023-03-16T17:34:43","date_gmt":"2023-03-16T21:34:43","guid":{"rendered":"https:\/\/baiedurfe.ca\/?p=4002"},"modified":"2023-03-16T17:34:43","modified_gmt":"2023-03-16T21:34:43","slug":"le-14-fevrier-2023","status":"publish","type":"post","link":"https:\/\/baiedurfe.ca\/fr\/le-14-fevrier-2023\/","title":{"rendered":"le 14 fevrier 2023"},"content":{"rendered":"<p><strong>Notes sur la r\u00e9union du Conseil tenue le 14 f\u00e9vrier 2023<\/strong><\/p>\n<p>Ces notes repr\u00e9sentent un r\u00e9sum\u00e9.\u00a0 La<a href=\"https:\/\/www.webtv.coop\/channel\/video\/20232D2D022D14-Conseil-municipal-de-la-ville-de-Baie-d26230393BUrfe\/ab4b900f4f9bb2ca16e69f3f7c218e13\/3\"> r\u00e9union<\/a> et<a href=\"https:\/\/www.baie-durfe.qc.ca\/medias\/en\/documents\/2023-02-14_ODJ_S%C3%A9ance_ordinaire.pdf\"> l\u2019ordre du jour<\/a> se trouvent, dans leur enti\u00e8ret\u00e9,\u00a0 sur le site\u00a0 de la Ville.<\/p>\n<p><strong>Interrogations du public<\/strong><\/p>\n<p>Nancy Mersereau, 13 Apple Hill \u2013 les feux d&rsquo;artifice sont-ils l\u00e9gaux \u00e0 l&rsquo;int\u00e9rieur des limites de la ville ? Le DG Bouchard r\u00e9pond que les feux d&rsquo;artifice doivent avoir un permis d\u00e9livr\u00e9 par le service d&rsquo;incendie. S&rsquo;il vous pla\u00eet signaler tout \u00e0 la police. Le cmdt Couture a recommand\u00e9 d&rsquo;appeler le 9-1-1 dans de telles circonstances.<\/p>\n<p>&nbsp;<\/p>\n<p>Joe Kranitz, 46 David-Kennedy &#8211; chaque ville entourant BDU dispose de courts de tennis gratuits \u00e0 l&rsquo;usage des citoyens, en particulier des jeunes; la Ville serait-elle int\u00e9ress\u00e9e \u00e0 construire des courts de tennis gratuits, en particulier \u00e0 l&rsquo;est de Morgan. Cllr Bissada a r\u00e9pondu que les courts de tennis n&rsquo;\u00e9taient pas actuellement pr\u00e9vus car il y a du temps public disponible sur les courts de tennis existants dimanche. Actuellement, ils concentrent leurs efforts sur l&rsquo;am\u00e9lioration des parcs pour r\u00e9pondre aux besoins des enfants en pleine croissance de la ville.<\/p>\n<p>&nbsp;<\/p>\n<p>Aria Campbell-Kelly, 720 Surrey \u2013 qui entretient les zones bois\u00e9es de la ville ? Il y a des d\u00e9charges ill\u00e9gales et, \u00e0 Surrey, un arbre tomb\u00e9 obstrue une partie de la route. Que peut-on faire pour approfondir notre prise en charge des espaces verts par l&rsquo;action\u00a0? Cllr Lowensteyn a r\u00e9pondu que les travaux publics surveillent ces zones r\u00e9guli\u00e8rement et n&rsquo;ont pas, aujourd&rsquo;hui, trouv\u00e9 un arbre obstruant la route. Ces zones foresti\u00e8res sont laiss\u00e9es \u00e0 leur \u00e9tat naturel; ils ne sont pas travers\u00e9s par des chemins construits par la ville. N\u00e9anmoins, s&rsquo;il y a dumping, il faut le signaler. Mme Campbell-Kelly a pr\u00e9cis\u00e9 que l&rsquo;arbre tomb\u00e9 empi\u00e8te sur l&rsquo;accotement de la route et que des ordures sont laiss\u00e9es r\u00e9guli\u00e8rement &#8211; les ordures d&rsquo;\u00e9t\u00e9 pourraient-elles \u00eatre laiss\u00e9es toute l&rsquo;ann\u00e9e. Le maire a demand\u00e9 que la question soit pos\u00e9e \u00e0 l&rsquo;administration et qu&rsquo;une r\u00e9ponse suive.<\/p>\n<p>&nbsp;<\/p>\n<p>Yves Lamoureux, 307 Victoria \u2013 pourquoi y a-t-il une diff\u00e9rence entre les taux des comptes de taxes pour les sommes emprunt\u00e9es pour le projet A40-route de desserte\/Lakeshore-ouest et le projet Lakeview\/Sunny Acres ? Le DG Bouchard a r\u00e9pondu que les projets \u00e9taient deux r\u00e8glements d&#8217;emprunt diff\u00e9rents, le premier est capital et int\u00e9r\u00eat pour une ann\u00e9e compl\u00e8te et le second est int\u00e9r\u00eat seulement pour six mois.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Rapport du SPVM \u2013 Commandant Couture<\/strong><\/p>\n<p>Pour les mois de janvier et f\u00e9vrier \u00e0 ce jour 2023, il y a eu des op\u00e9rations de vitesse sur Lakeshore devant Whiteside Taylor. La plupart des contraventions \u00e9mises \u00e9taient destin\u00e9es aux habitants de la ville ou aux parents d&rsquo;enfants de l&rsquo;\u00e9cole. La patrouille \u00e0 v\u00e9lo \u00e9tait \u00e0 Allans Hill le 23 janvier avec l&rsquo;\u00e9quipe de sauvetage pour les activit\u00e9s de plein air. La police a r\u00e9pondu \u00e0 un appel au parc canin Bertold le 28 janvier pour un signalement de chiens agressifs; un suivi a \u00e9t\u00e9 fait avec toutes les parties concern\u00e9es. Le 29 janvier, la patrouille \u00e0 v\u00e9lo \u00e9tait \u00e0 Fritz pour l&rsquo;\u00e9v\u00e9nement de fat-bike parrain\u00e9 par la Ville; de plus, ils \u00e9taient chez Joseph-Henrico le 31 janvier dernier pour un \u00e9v\u00e9nement de fat-bike. Les agents communautaires \u00e9taient \u00e0 l&rsquo;\u00e9cole Alexander Von Humboldt le 24 janvier pour pr\u00e9senter des conseils de s\u00e9curit\u00e9. Il n&rsquo;y a pas eu d&rsquo;\u00e9v\u00e9nements ou d&rsquo;incidents majeurs \u00e0 Baie-D&rsquo;Urf\u00e9 durant cette p\u00e9riode. Soyez conscient de l&rsquo;arnaque des \u00ab\u00a0grands-parents\u00a0\u00bb qui circule. En cas de doute, demandez les coordonn\u00e9es, raccrochez et rappelez-les ou, mieux encore, contactez la police.<\/p>\n<p>Il a \u00e9t\u00e9 rappel\u00e9 que les citoyens peuvent contacter la station au 514 280 0101 ou p&#100;&#x71;&#x31;&#64;&#115;&#112;&#x76;&#x6d;&#46;&#113;&#x63;&#x2e;c&#97;.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Rapport du maire<\/strong><\/p>\n<p>Les maires et directeurs g\u00e9n\u00e9raux des municipalit\u00e9s d\u00e9fusionn\u00e9es (15) se sont r\u00e9unis pour une s\u00e9ance de remue-m\u00e9ninges sur la fa\u00e7on de traiter avec la Ville de Montr\u00e9al Agglom\u00e9ration. Le prochain \u00e9v\u00e9nement World Caf\u00e9 pour les commentaires des citoyens sur la r\u00e9forme des statuts aura lieu le 18 mars \u00e0 Alexander Von Humboldt. Le comit\u00e9 de l&rsquo;environnement a soumis des recommandations au conseil pour examen; ceux-ci seront \u00e9galement examin\u00e9s par l&rsquo;administration avant d&rsquo;\u00eatre remis au public. Le comit\u00e9 des parcs et des loisirs travaille \u00e0 la planification de la r\u00e9novation du parc John Weir. Le maire a \u00e9galement assist\u00e9 \u00e0 l&rsquo;AGA de l&rsquo;Escouade de sauvetage et a rappel\u00e9 \u00e0 tous le Caf\u00e9 D&rsquo;Urf\u00e9 tenu tous les mercredis de 10h00 \u00e0 15h00 dans l&rsquo;\u00e9difice du club de curling. Elle a \u00e9galement remerci\u00e9 Oana Silaghi pour l&rsquo;organisation de l&rsquo;\u00e9v\u00e9nement artisanal de la Saint-Valentin \u00e0 la biblioth\u00e8que le 11 f\u00e9vrier. Pour suivre les \u00e9v\u00e9nements en ville, veuillez lire les Nouvelles et opinions, suivez la Ville sur Facebook et\/ou inscrivez-vous au Mail Chimp de la Ville.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Rapports des conseillers<\/strong><\/p>\n<p><u>Cllr Bissada<\/u> a mentionn\u00e9 que le programme Lunch &amp; Learn \u00e9tait de retour en mars et que Demystifying Diabetes sera pr\u00e9sent\u00e9. Le Rendez-vous des a\u00een\u00e9s a eu lieu le 16 f\u00e9vrier \u00e0 la Grange rouge et a \u00e9t\u00e9 bien fr\u00e9quent\u00e9. La Journ\u00e9e internationale de la femme est le 8 mars et l&rsquo;Association des citoyens tiendra son \u00e9v\u00e9nement associ\u00e9 le 10 mars.<\/p>\n<p><u>Cllr Lowensteyn<\/u> rapporte que le Conseil Junior tiendra sa r\u00e9union mensuelle \u00e0 la Biblioth\u00e8que le 21 f\u00e9vrier \u00e0 19h00 et que sa prochaine Soir\u00e9e Jeux aura lieu le 24 f\u00e9vrier \u00e0 19h00 \u00e0 la Biblioth\u00e8que. Le Junior Council a une page Instagram et vous invite \u00e0 les suivre.<\/p>\n<p><u>Cllr Brown <\/u>a pr\u00e9sent\u00e9 un rapport sur les activit\u00e9s de Rescue Squad (315 heures en janvier). Ils ont tenu leur 16e assembl\u00e9e g\u00e9n\u00e9rale annuelle. Cllr Brown a \u00e9galement pr\u00e9sent\u00e9 un bilan des activit\u00e9s 2022. Ils ont aussi particip\u00e9 \u00e0 une recherche de personne disparue \u00e0 St-Michel des Saints le 20 janvier. Ils sont pr\u00e9sents tous les week-ends \u00e0 Allans Hill pour prodiguer les premiers soins si n\u00e9cessaire. N&rsquo;h\u00e9sitez pas \u00e0 venir dire bonjour aux membres \u00e0 n&rsquo;importe quel \u00e9v\u00e9nement.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Rapport du Directeur g\u00e9n\u00e9ral<\/strong><\/p>\n<p>Le mois de janvier est g\u00e9n\u00e9ralement consacr\u00e9 \u00e0 la planification et \u00e0 la pr\u00e9paration des \u00e9v\u00e9nements \u00e0 venir, par ex. le caf\u00e9 du monde. Ils ont consacr\u00e9 beaucoup de temps \u00e0 la pr\u00e9paration du projet de mairie ; des mises \u00e0 jour sont disponibles sur la page Projets de d\u00e9veloppement du site Web de la Ville. Deux cam\u00e9ras seront install\u00e9es sur place qui prendront des photos fixes qui seront affich\u00e9es sur le site Web et incluses dans une pr\u00e9sentation vid\u00e9o \u00e0 la fin du projet.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Administration<\/strong><\/p>\n<p>Le rapport sur la gestion contractuelle pour 2022 est d\u00e9pos\u00e9. La Ville a lanc\u00e9 20 appels d&rsquo;offres, sign\u00e9 des renouvellements de deux contrats, sign\u00e9 15 contrats de gr\u00e9 \u00e0 gr\u00e9. Le tout en conformit\u00e9 avec le r\u00e8glement 1068. Un contrat a \u00e9t\u00e9 accord\u00e9 \u00e0 MuniPaaS Inc. pour le logiciel Salesforce pour un syst\u00e8me en ligne pour recevoir les demandes\/plaintes \u00e0 Travaux publics des r\u00e9sidents.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Finance<\/strong><\/p>\n<p>Les d\u00e9caissements en esp\u00e8ces de la p\u00e9riode 13 de 2022 et de janvier 2023 ont totalis\u00e9 1 547 621,71 $. Il y a eu de nombreux d\u00e9bours importants dont des paiements sur le contrat de d\u00e9neigement, pour l&rsquo;achat de sel de voirie, etc.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Parcs, loisirs et environnement<\/strong><\/p>\n<p>Un contrat a \u00e9t\u00e9 accord\u00e9 pour les services professionnels concernant les am\u00e9liorations du parc Bertold; une entente au montant de 75 000 $ a \u00e9t\u00e9 conclue entre la Ville et le GRAME pour la participation au programme \u00ab Ensemble on verdit \u00bb; conform\u00e9ment aux r\u00e9centes modifications de la loi provinciale concernant les installations septiques, les employ\u00e9s actuels du personnel de l&rsquo;environnement et de l&rsquo;urbanisme ont \u00e9t\u00e9 nomm\u00e9s inspecteurs.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Travaux Publics et Infrastructures de la Ville<\/strong><\/p>\n<p>Des contrats ont \u00e9t\u00e9 octroy\u00e9s pour modifier les plans de r\u00e9fection du chemin d&rsquo;acc\u00e8s entre Clark-Graham et la station EXO, pour analyser la viabilit\u00e9 de la conversion \u00e0 l&rsquo;\u00e9lectricit\u00e9 du parc automobile de la Ville, pour bonifier le programme de vidange et d&rsquo;inspection des fosses septiques et pour la supervision des travaux m\u00e9caniques et \u00e9lectriques du projet de l&rsquo;h\u00f4tel de ville.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Services aux citoyens et affaires communautaires<\/strong><\/p>\n<p>Il y avait deux r\u00e9cipiendaires de subventions pour le programme Support for Excellence, Zihan Peng a re\u00e7u 200 $ pour son excellence en badminton national et Evandra Zlobec a re\u00e7u 200 $ pour sa participation \u00e0 la gymnastique artistique internationale \u00e0 Gatineau et en Saskatchewan.<\/p>\n<p>La Ville subventionnera \u00e0 nouveau l&rsquo;adh\u00e9sion des r\u00e9sidents \u00e0 l&rsquo;Arboretum Morgan.<\/p>\n<p>Un don de 150 $ a \u00e9t\u00e9 fait \u00e0 la Loyalist Humane Society en m\u00e9moire d&rsquo;Anna Tait, m\u00e8re de Linda Tait et r\u00e9sidente de la Ville de 1953 \u00e0 1983.<\/p>\n<p><em>Linda Tait<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Notes sur la r\u00e9union du Conseil tenue le 14 f\u00e9vrier 2023 Ces notes repr\u00e9sentent un r\u00e9sum\u00e9.\u00a0 La r\u00e9union et l\u2019ordre du jour se trouvent, dans leur enti\u00e8ret\u00e9,\u00a0 sur le site\u00a0 de la Ville. Interrogations du public Nancy Mersereau, 13 Apple Hill \u2013 les feux d&rsquo;artifice sont-ils l\u00e9gaux \u00e0 l&rsquo;int\u00e9rieur des limites de la ville ? [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[18],"tags":[],"class_list":["post-4002","post","type-post","status-publish","format-standard","hentry","category-extraits-du-conseil-municipal"],"_links":{"self":[{"href":"https:\/\/baiedurfe.ca\/fr\/wp-json\/wp\/v2\/posts\/4002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/baiedurfe.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/baiedurfe.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/baiedurfe.ca\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/baiedurfe.ca\/fr\/wp-json\/wp\/v2\/comments?post=4002"}],"version-history":[{"count":2,"href":"https:\/\/baiedurfe.ca\/fr\/wp-json\/wp\/v2\/posts\/4002\/revisions"}],"predecessor-version":[{"id":4020,"href":"https:\/\/baiedurfe.ca\/fr\/wp-json\/wp\/v2\/posts\/4002\/revisions\/4020"}],"wp:attachment":[{"href":"https:\/\/baiedurfe.ca\/fr\/wp-json\/wp\/v2\/media?parent=4002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/baiedurfe.ca\/fr\/wp-json\/wp\/v2\/categories?post=4002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/baiedurfe.ca\/fr\/wp-json\/wp\/v2\/tags?post=4002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}